{"id":359973,"date":"2023-03-17T18:01:06","date_gmt":"2023-03-17T21:01:06","guid":{"rendered":"https:\/\/www.planbnoticias.com.ar\/?p=359973"},"modified":"2023-03-17T18:01:51","modified_gmt":"2023-03-17T21:01:51","slug":"la-bancaria-cerro-acuerdo-salarial-de-325-hasta-mayo-y-compensacion-por-ganancias","status":"publish","type":"post","link":"https:\/\/www.planbnoticias.com.ar\/index.php\/2023\/03\/17\/la-bancaria-cerro-acuerdo-salarial-de-325-hasta-mayo-y-compensacion-por-ganancias\/","title":{"rendered":"La Bancaria cerr\u00f3 acuerdo salarial de 32,5% hasta mayo y compensaci\u00f3n por Ganancias"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-359974\" src=\"https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2023\/03\/sergio-palazzo-bancarios.jpg\" alt=\"\" width=\"792\" height=\"631\" srcset=\"https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2023\/03\/sergio-palazzo-bancarios.jpg 792w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2023\/03\/sergio-palazzo-bancarios-300x239.jpg 300w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2023\/03\/sergio-palazzo-bancarios-768x612.jpg 768w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2023\/03\/sergio-palazzo-bancarios-585x466.jpg 585w\" sizes=\"(max-width: 792px) 100vw, 792px\" \/><\/p>\n<p>De esta manera, desde mayo el salario inicial de un trabajador bancario ser\u00e1 de $312.897 mensuales.<\/p>\n<p><script async src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script><br \/>\n<!-- Publi m\u00f3vil interior nota --><br \/>\n<ins class=\"adsbygoogle\" style=\"display: inline-block; width: 320px; height: 100px;\" data-ad-client=\"ca-pub-7250018434179914\" data-ad-slot=\"1040343543\"><\/ins><br \/>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script><\/p>\n<p>La Bancaria, el gremio que encabeza el diputado nacional Sergio Palazzo, anunci\u00f3 este viernes que cerr\u00f3 la primera etapa de la negociaci\u00f3n paritaria hasta el mes de mayo, cuando se active la cl\u00e1sula de revisi\u00f3n. Los trabajadores bancarios recibir\u00e1n un aumento del 32,5% m\u00e1s una compensaci\u00f3n por el impuesto a las Ganancias.<\/p>\n<p>El sindicato inform\u00f3 en un comunicado que se acord\u00f3 con las c\u00e1maras empresarias ABAPPRA, ADEBA, ABA y el BCRA un un reconocimiento sobre la paritaria 2022 del 0.7% y para el a\u00f1o 2023 un incremento al mes de mayo de 32,5%, desglosado de la siguiente manera: en 4 tramos: 6% para enero 2023; 7,1% para febrero 2023; 11% para marzo 2023 y 8,4 % mayo 2023.<\/p>\n<p>De esta manera, desde mayo el salario inicial de un trabajador bancario ser\u00e1 de $312.897 mensuales.<\/p>\n<p>Adem\u00e1s, se acord\u00f3 un pago extraordinario, para todos los trabajadores, en compensaci\u00f3n por Ganancias, pagadero el 50% en mayo y el 50% restante en septiembre de 2023.<\/p>\n<p>En el caso de los bancos que devuelven el impuesto a las ganancias a sus trabajadores, no abonar\u00e1n dicho bono, salvo en los casos de aquellos trabajadores que por su nivel de ingresos no tengan devoluci\u00f3n de dicho impuesto..<\/p>\n<p>\u00abDe esta manera se disminuye considerablemente el impacto salarial del impuesto a las ganancias sobre el trabajador\/ra que paga este tributo, partiendo de la base que siempre sostuvo nuestro Sindicato que el salario no es ganancia, logrando con el presente acuerdo un significativo alivio en los bancarios\/as que pagan este injusto impuesto\u00bb, indic\u00f3 el gremio en un comunicado.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"zxx\"><a href=\"https:\/\/t.co\/uXGDiWMfzk\">pic.twitter.com\/uXGDiWMfzk<\/a><\/p>\n<p>\u2014 Sergio Omar Palazzo (@SergioOPalazzo) <a href=\"https:\/\/twitter.com\/SergioOPalazzo\/status\/1636811340261015554?ref_src=twsrc%5Etfw\">March 17, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De esta manera, desde mayo el salario inicial de un trabajador bancario ser\u00e1 de $312.897 mensuales. La Bancaria, el gremio que encabeza el diputado nacional Sergio Palazzo, anunci\u00f3 este viernes&hellip;<\/p>\n","protected":false},"author":5,"featured_media":359974,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,12],"tags":[],"class_list":["post-359973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gremiales","category-pais"],"jetpack_featured_media_url":"https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2023\/03\/sergio-palazzo-bancarios.jpg","_links":{"self":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/359973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=359973"}],"version-history":[{"count":2,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/359973\/revisions"}],"predecessor-version":[{"id":359976,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/359973\/revisions\/359976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/media\/359974"}],"wp:attachment":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=359973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=359973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=359973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}