{"id":512076,"date":"2026-09-02T09:22:52","date_gmt":"2026-09-02T12:22:52","guid":{"rendered":"https:\/\/www.planbnoticias.com.ar\/?p=512076"},"modified":"2026-09-02T09:22:52","modified_gmt":"2026-09-02T12:22:52","slug":"lanzaron-plan-de-regularizacion-en-pico-15-de-descuento-y-hasta-12-cuotas-para-cancelar-deudas-municipales","status":"publish","type":"post","link":"https:\/\/www.planbnoticias.com.ar\/index.php\/2026\/09\/02\/lanzaron-plan-de-regularizacion-en-pico-15-de-descuento-y-hasta-12-cuotas-para-cancelar-deudas-municipales\/","title":{"rendered":"Lanzaron plan de regularizaci\u00f3n en Pico: 15% de descuento y hasta 12 cuotas para cancelar deudas municipales"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-499660\" src=\"https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico.jpeg\" alt=\"\" width=\"1600\" height=\"899\" srcset=\"https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico.jpeg 1600w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico-300x169.jpeg 300w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico-1024x575.jpeg 1024w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico-768x432.jpeg 768w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico-1536x863.jpeg 1536w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico-1170x657.jpeg 1170w, https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico-585x329.jpeg 585w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><\/p>\n<p>La Municipalidad de General Pico informa que, a partir de este 1 de septiembre, comenzar\u00e1 la tercera etapa del Plan de Regularizaci\u00f3n de Deudas, que se extender\u00e1 hasta el 30 del mismo mes.<\/p>\n<p>Durante este per\u00edodo, las y los contribuyentes podr\u00e1n acceder a un 15% de descuento por pago al contado de sus obligaciones tributarias. Podr\u00e1 efectuarse mediante efectivo, transferencia bancaria, bot\u00f3n de pago, tarjeta de cr\u00e9dito en un pago o con tarjetas Visa y MasterCard Cald\u00e9n del Banco de La Pampa en las condiciones vigentes de la entidad financiera.<\/p>\n<p><strong>Plan de pagos<\/strong><\/p>\n<p>Tambi\u00e9n se podr\u00e1 acceder a planes de regularizaci\u00f3n de hasta 12 cuotas mensuales sin inter\u00e9s.<\/p>\n<p><strong>Infracciones<\/strong><\/p>\n<p>Las infracciones con sentencia firme que se encuentren en la Oficina de Apremios de la Direcci\u00f3n de Rentas podr\u00e1n cancelarse mediante pago contado con un descuento del 45% sobre el monto total adeudado hasta el 30 de septiembre de 2026.<\/p>\n<p><strong>Reconocimiento a contribuyentes<\/strong><\/p>\n<p>El plan tambi\u00e9n contempla un beneficio para quienes mantienen sus obligaciones municipales al d\u00eda. El 10% de lo recaudado a trav\u00e9s de los pagos de contado realizados en el marco de este r\u00e9gimen ser\u00e1 destinado a la generaci\u00f3n de cr\u00e9ditos fiscales para los contribuyentes cumplidores.<\/p>\n<p>La medida alcanzar\u00e1 a quienes no registren deudas exigibles con la Municipalidad al momento de la promulgaci\u00f3n de la ordenanza. El cr\u00e9dito se aplicar\u00e1 desde el primer per\u00edodo fiscal de 2027, como reconocimiento al cumplimiento sostenido de sus obligaciones tributarias.<\/p>\n<p>Para m\u00e1s informaci\u00f3n o para adherir al r\u00e9gimen, las personas interesadas pueden acercarse a la Direcci\u00f3n de Rentas, ubicada en calle 11 entre Avenida San Mart\u00edn y calle 16, o consultar a trav\u00e9s de los canales oficiales de la Municipalidad de General Pico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Municipalidad de General Pico informa que, a partir de este 1 de septiembre, comenzar\u00e1 la tercera etapa del Plan de Regularizaci\u00f3n de Deudas, que se extender\u00e1 hasta el 30&hellip;<\/p>\n","protected":false},"author":3,"featured_media":499660,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-512076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"jetpack_featured_media_url":"https:\/\/www.planbnoticias.com.ar\/wp-content\/uploads\/2026\/05\/rentas-pico.jpeg","_links":{"self":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/512076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/comments?post=512076"}],"version-history":[{"count":1,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/512076\/revisions"}],"predecessor-version":[{"id":512077,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/posts\/512076\/revisions\/512077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/media\/499660"}],"wp:attachment":[{"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/media?parent=512076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/categories?post=512076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.planbnoticias.com.ar\/index.php\/wp-json\/wp\/v2\/tags?post=512076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}